{"id":479,"date":"2022-04-25T18:48:20","date_gmt":"2022-04-25T18:48:20","guid":{"rendered":"https:\/\/www.saamtowage.com\/guatemala\/?page_id=479"},"modified":"2026-05-28T22:31:16","modified_gmt":"2026-05-28T22:31:16","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/www.saamtowage.com\/guatemala\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;6%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;6%&#8221; top_padding_tablet=&#8221;20%&#8221; top_padding_phone=&#8221;25%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;fade-in&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin_tablet=&#8221;20&#8243; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;4\/5&#8243; tablet_width_inherit=&#8221;small_desktop&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_col-md-9&#8243;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h1&#8243; line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; stagger_animation=&#8221;true&#8221; mobile_disable_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Contact Us&#8221; font_size=&#8221;8vw&#8221; font_size_tablet=&#8221;9vw&#8221; font_size_phone=&#8221;10vw&#8221;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;10px&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;small_desktop&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; mobile_disable_entrance_animation=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;500&#8243; offset=&#8221;vc_col-md-3&#8243;][nectar_cta btn_style=&#8221;underline&#8221; heading_tag=&#8221;h6&#8243; text_color=&#8221;#0a0a0a&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inline-block&#8221; link_text=&#8221;Contact map&#8221; url=&#8221;#map&#8221; margin_right=&#8221;25&#8243;][nectar_cta btn_style=&#8221;underline&#8221; heading_tag=&#8221;h6&#8243; text_color=&#8221;#0a0a0a&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inline-block&#8221; link_text=&#8221;Let&#8217;s Talk&#8221; url=&#8221;#talk&#8221; margin_right=&#8221;25&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;3%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;10\/12&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_gradient_text heading_tag=&#8221;h2&#8243; color=&#8221;extra-color-gradient-1&#8243; gradient_direction=&#8221;diagonal&#8221; text=&#8221;In port or on the high seas,<br \/>\nwe assist with a variety of maritime operations,<br \/>\ndelivering reliability, operational excellence, safety<br \/>\nand experience.&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;map&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_image_with_hotspots image=&#8221;488&#8243; preview=&#8221;https:\/\/www.saamtowage.com\/guatemala\/wp-content\/uploads\/sites\/18\/2022\/04\/Mapa_negro.jpg&#8221; color_1=&#8221;Accent-Color&#8221; hotspot_icon=&#8221;plus_sign&#8221; tooltip=&#8221;click&#8221; tooltip_shadow=&#8221;none&#8221;]\n[\/nectar_hotspot][nectar_hotspot left=&#8221;50.4157%&#8221; top=&#8221;74.7015%&#8221; position=&#8221;left&#8221;]<strong>CHILE<\/strong><br \/>\n<strong> Commercial Manager<br \/>\n<\/strong><br \/>\n<a href=\"mailto:commercial.chile@saamtowage.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8035 size-full\" src=\"https:\/\/www.saamtowage.com\/chile\/wp-content\/uploads\/sites\/13\/2022\/05\/email-e1652111940960.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"mailto:commercial.chile@saamtowage.com\"> commercial.chile@saamtowage.com<\/a><\/p>\n[\/nectar_hotspot][nectar_hotspot left=&#8221;48.7479%&#8221; top=&#8221;66.4733%&#8221; position=&#8221;left&#8221;]<strong>PERU<\/strong><br \/>\n<strong>Commercial Manager<br \/>\n<\/strong><br \/>\n<a href=\"mailto:commercial.peru@saamtowage.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8035 size-full\" src=\"https:\/\/www.saamtowage.com\/peru\/wp-content\/uploads\/sites\/17\/2022\/05\/email-e1652111940960.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"mailto:commercial.peru@saamtowage.com\"> commercial.peru@saamtowage.com<\/a><br \/>\n<a href=\"tel:+51972507866\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8038 size-full\" src=\"https:\/\/www.saamtowage.com\/peru\/wp-content\/uploads\/sites\/17\/2022\/05\/phone-call-e1652111995544.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"tel:+51972507866\">+51 972 507 866<\/a><br \/>\n[\/nectar_hotspot][nectar_hotspot left=&#8221;47.1898%&#8221; top=&#8221;58.5941%&#8221; position=&#8221;left&#8221;]<strong>ECUADOR<\/strong><\/p>\n<p><a href=\"mailto:commercial.ecuador@saamtowage.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8035 size-full\" src=\"https:\/\/www.saamtowage.com\/ecuador\/wp-content\/uploads\/sites\/14\/2022\/05\/email-e1652111940960.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"mailto:commercial.ecuador@saamtowage.com\">commercial.ecuador@saamtowage.com<\/a><br \/>\n[\/nectar_hotspot][nectar_hotspot left=&#8221;55.0868%&#8221; top=&#8221;79.4263%&#8221; position=&#8221;right&#8221;]<strong>URUGUAY<\/strong><\/p>\n<p><a href=\"mailto:commercial.uruguay@saamtowage.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8035 size-full\" src=\"https:\/\/www.saamtowage.com\/uruguay\/wp-content\/uploads\/sites\/10\/2022\/05\/email-e1652111940960.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"mailto:commercial.uruguay@saamtowage.com\"> commercial.uruguay@saamtowage.com<\/a><\/p>\n[\/nectar_hotspot][nectar_hotspot left=&#8221;39.1764%&#8221; top=&#8221;43.9095%&#8221; position=&#8221;left&#8221;]<strong>MEXICO<\/strong><br \/>\n<strong>Commercial Manager<br \/>\n<\/strong><br \/>\n<a href=\"mailto:commercial.mexico@saamtowage.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8035 size-full\" src=\"https:\/\/www.saamtowage.com\/mexico\/wp-content\/uploads\/sites\/9\/2022\/05\/email-e1652111940960.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"mailto:commercial.mexico@saamtowage.com\"> commercial.mexico@saamtowage.com<\/a><br \/>\n<a href=\"tel:+525552803025\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8038 size-full\" src=\"https:\/\/www.saamtowage.com\/mexico\/wp-content\/uploads\/sites\/9\/2022\/05\/phone-call-e1652111995544.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"tel:+525559790200\">+52 55 5979 0200<\/a><\/p>\n[\/nectar_hotspot][nectar_hotspot left=&#8221;41.1764%&#8221; top=&#8221;48.9095%&#8221; position=&#8221;left&#8221;]<strong>GUATEMALA<\/strong><br \/>\n<strong>Commercial Manager<br \/>\n<\/strong><br \/>\n<a href=\"mailto:commercial.guatemala@saamtowage.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8035 size-full\" src=\"https:\/\/www.saamtowage.com\/mexico\/wp-content\/uploads\/sites\/9\/2022\/05\/email-e1652111940960.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"mailto:commercial.guatemala@saamtowage.com\"> commercial.guatemala@saamtowage.com<\/a><br \/>\n<a href=\"tel:+50223374328\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8038 size-full\" src=\"https:\/\/www.saamtowage.com\/mexico\/wp-content\/uploads\/sites\/9\/2022\/05\/phone-call-e1652111995544.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"tel:+50223374328\">+502 2337 4328<\/a><br \/>\n[\/nectar_hotspot][nectar_hotspot left=&#8221;56.7579%&#8221; top=&#8221;67.0371%&#8221; position=&#8221;right&#8221;]<strong>BRAZIL<\/strong><br \/>\n<strong>Commercial Manager<br \/>\n<\/strong><br \/>\n<a href=\"mailto:danielle.fagundes@saamtowage.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8035 size-full\" src=\"https:\/\/www.saamtowage.com\/brazil\/wp-content\/uploads\/sites\/2\/2022\/05\/email-e1652111940960.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"mailto:danielle.fagundes@saamtowage.com\">commercial.brazil@saamtowage.com <\/a><br \/>\n<a href=\"tel:+5521995777077\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8038 size-full\" src=\"https:\/\/www.saamtowage.com\/brazil\/wp-content\/uploads\/sites\/2\/2022\/05\/phone-call-e1652111995544.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"tel:+552121211000\"> + 55 21 2121 1000 <\/a><br \/>\n[\/nectar_hotspot][nectar_hotspot left=&#8221;37.0668%&#8221; top=&#8221;16.7081%&#8221; position=&#8221;left&#8221;]<strong>CANADA<\/strong><br \/>\n<strong>Commercial Manager<br \/>\n<\/strong><br \/>\n<a href=\"mailto:tpow@saamtowage.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8035 size-full\" src=\"https:\/\/www.saamtowage.com\/canada\/wp-content\/uploads\/sites\/3\/2022\/05\/email-e1652111940960.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"mailto:commercial.canada@saamtowage.com\"> commercial.canada@saamtowage.com<\/a><br \/>\n<a href=\"tel:+16042507354\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8038 size-full\" src=\"https:\/\/www.saamtowage.com\/canada\/wp-content\/uploads\/sites\/3\/2022\/05\/phone-call-e1652111995544.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"tel:+16042507354\"> + 1 604 250 7354 <\/a><br \/>\n<a href=\"tel:+16042510202\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8038 size-full\" src=\"https:\/\/www.saamtowage.com\/canada\/wp-content\/uploads\/sites\/3\/2022\/05\/phone-call-e1652111995544.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"tel:+16042510202\"> + 1 604 251 0202<\/a><br \/>\n[\/nectar_hotspot][nectar_hotspot left=&#8221;49.1898%&#8221; top=&#8221;55.5941%&#8221; position=&#8221;right&#8221;]<strong>COLOMBIA<\/strong><\/p>\n<p><a href=\"mailto:lmotero@saamtowage.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8035 size-full\" src=\"https:\/\/www.saamtowage.com\/colombia\/wp-content\/uploads\/sites\/6\/2022\/05\/email-e1652111940960.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"mailto:commercial.colombia@saamtowage.com\">commercial.colombia@saamtowage.com<\/a><\/p>\n[\/nectar_hotspot][nectar_hotspot left=&#8221;43.1111%&#8221; top=&#8221;49.1377%&#8221; position=&#8221;left&#8221;]<strong>EL SALVADOR<\/strong><br \/>\n<strong>Commercial Manager<br \/>\n<\/strong><br \/>\n<a href=\"mailto:commercial.elsalvador@saamtowage.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8035 size-full\" src=\"https:\/\/www.saamtowage.com\/elsalvador\/wp-content\/uploads\/sites\/16\/2022\/05\/email-e1652111940960.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"mailto:commercial.elsalvador@saamtowage.com\"> commercial.elsalvador@saamtowage.com<\/a><br \/>\n<a href=\"tel:+50640019752\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8038 size-full\" src=\"https:\/\/www.saamtowage.com\/elsalvador\/wp-content\/uploads\/sites\/16\/2022\/05\/phone-call-e1652111995544.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"tel:+50640019752\">+506 4001 9752<\/a><\/p>\n[\/nectar_hotspot][nectar_hotspot left=&#8221;44.1411%&#8221; top=&#8221;52.1377%&#8221; position=&#8221;left&#8221;]<strong>COSTA RICA<\/strong><br \/>\n<strong>Commercial Manager<br \/>\n<\/strong><br \/>\n<a href=\"mailto:commercial.costarica@saamtowage.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8035 size-full\" src=\"https:\/\/www.saamtowage.com\/elsalvador\/wp-content\/uploads\/sites\/16\/2022\/05\/email-e1652111940960.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"mailto:commercial.costarica@saamtowage.com\"> commercial.costarica@saamtowage.com<\/a><br \/>\n<a href=\"tel:+50640019752\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8038 size-full\" src=\"https:\/\/www.saamtowage.com\/elsalvador\/wp-content\/uploads\/sites\/16\/2022\/05\/phone-call-e1652111995544.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"tel:+50640019752\">+506 4001 9752<\/a><\/p>\n[\/nectar_hotspot][nectar_hotspot left=&#8221;46.2994%&#8221; top=&#8221;52.9364%&#8221; position=&#8221;left&#8221;]<strong>PANAMA<\/strong><br \/>\n<strong>Commercial Manager<br \/>\n<\/strong><br \/>\n<a href=\"mailto:commercial.panama@SAAMtowage.com\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8035 size-full\" src=\"https:\/\/www.saamtowage.com\/panama\/wp-content\/uploads\/sites\/11\/2022\/05\/email-e1652111940960.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"mailto:commercial.panama@SAAMtowage.com\"> commercial.panama@SAAMtowage.com<\/a><br \/>\n<a href=\"tel:+50769480498\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8038 size-full\" src=\"https:\/\/www.saamtowage.com\/panama\/wp-content\/uploads\/sites\/11\/2022\/05\/phone-call-e1652111995544.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"tel:+50769480498\"> +507 6948 0498<br \/>\n<\/a><a href=\"tel:+5078315020\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8038 size-full\" src=\"https:\/\/www.saamtowage.com\/panama\/wp-content\/uploads\/sites\/11\/2022\/05\/phone-call-e1652111995544.png\" alt=\"\" width=\"30\" height=\"30\" \/><\/a><a href=\"tel:+5078315020\"> +507 831 5020<\/a><\/p>\n[\/nectar_hotspot][\/nectar_image_with_hotspots][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#efefef&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; overflow=&#8221;visible&#8221; id=&#8221;talk&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_gradient_text heading_tag=&#8221;h1&#8243; color=&#8221;extra-color-gradient-1&#8243; gradient_direction=&#8221;horizontal&#8221; text=&#8221;Contact:&#8221;][vc_column_text]\n<div class=\"elementToProof\"><strong>Yacenys Contreras<\/strong><br \/>\n<a href=\"tel:+573207153830\">+57 320 715 3830<\/a><\/div>\n<p><a href=\"mailto:commercial.guatemala@saamtowage.com\">commercial.guatemala@saamtowage.com\u00a0<\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text]\n<h5 style=\"text-align: center;\">Let\u00b4s Talk.<\/h5>\n<h2 style=\"text-align: center;\">Complete the form<br \/>\nor contact our commercial executives<br \/>\nin each country (see map above).<\/h2>\n[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin=&#8221;-35%&#8221; column_element_spacing=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<p style=\"text-align: center;\"><div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-521\"><form id=\"wpforms-form-521\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"521\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/guatemala\/wp-json\/wp\/v2\/pages\/479\" data-token=\"e31db2528915b9cdf4326ce8d89e9e05\" data-token-time=\"1788363828\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-521-field_0-container\" class=\"wpforms-field wpforms-field-name wpforms-one-half wpforms-first\" data-field-type=\"name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-521-field_0\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-521-field_0\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][0]\" required><\/div><div id=\"wpforms-521-field_4-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half\" data-field-type=\"text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-521-field_4\">Company <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-521-field_4\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][4]\" required><\/div><div id=\"wpforms-521-field_1-container\" class=\"wpforms-field wpforms-field-email wpforms-one-half wpforms-first\" data-field-type=\"email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-521-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-521-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-521-field_5-container\" class=\"wpforms-field wpforms-field-phone wpforms-one-half\" data-field-type=\"phone\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-521-field_5\">Phone <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-521-field_5\" class=\"wpforms-field-large wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][5]\" aria-label=\"Phone\" required><\/div><div id=\"wpforms-521-field_6-container\" class=\"wpforms-field wpforms-field-select wpforms-one-half wpforms-first wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-521-field_6\">Subject <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-521-field_6\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][6]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Dropdown here<\/option><option value=\"Service Request\"  class=\"choice-1 depth-1\"  >Service Request<\/option><option value=\"Suggestions\"  class=\"choice-2 depth-1\"  >Suggestions<\/option><option value=\"Others\"  class=\"choice-3 depth-1\"  >Others<\/option><option value=\"Complains\"  class=\"choice-4 depth-1\"  >Complains<\/option><\/select><\/div><div id=\"wpforms-521-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-type=\"textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-521-field_2\">Message <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-521-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><div id=\"wpforms-521-field_7-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"7\"><label class=\"wpforms-field-label\">Disclaimer <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-521-field_7\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-521-field_7_1\" name=\"wpforms[fields][7][]\" value=\"I authorize SAAM S.A. and its subsidiaries and affiliated companies to process my personal data communicated through this form in order to communicate with me to respond to my contact request and the requirements that I have informed by this means.  The personal data provided through this form will not be communicated to responsible or controlled third parties, and will be used exclusively for the indicated purposes. If you have any queries, please contact protecciondedatos@saamtowage.cl\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-521-field_7_1\">I authorize SAAM S.A. and its subsidiaries and affiliated companies to process my personal data communicated through this form in order to communicate with me to respond to my contact request and the requirements that I have informed by this means.  The personal data provided through this form will not be communicated to responsible or controlled third parties, and will be used exclusively for the indicated purposes. If you have any queries, please contact protecciondedatos@saamtowage.cl<\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v2\" ><div class=\"g-recaptcha\" data-sitekey=\"6LdY9N4hAAAAAIPvz424p14mccTvr4MxMjMEMUik\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-recaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"521\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/pages\/479\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-521\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.saamtowage.com\/guatemala\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;6900&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;40%&#8221; bottom_padding=&#8221;10%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;Testimonials&#8221; color_overlay=&#8221;#0a0a0a&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;zoom-out-slow&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;none&#8221;]\n<h3>Contact.<\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;32px&#8221;][vc_column_text css_animation=&#8221;none&#8221;]\n<h5>Guatemala City<\/h5>\n<p>17 Ave. 19-70, Zone 10 Edificio Torino, Office 807.<br \/>\nGuatemala City, Guatemala<\/p>\n<p><a href=\"mailto:commercial.guatemala@saamtowage.com\">commercial.guatemala@saamtowage.com\u00a0<\/a><br \/>\n<a href=\"tel:+50223374328\">+502 2337 4328<\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; bottom_padding=&#8221;5%&#8221; left_padding_desktop=&#8221;6%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;6%&#8221; top_padding_tablet=&#8221;20%&#8221; top_padding_phone=&#8221;25%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;fade-in&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-479","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/pages\/479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/comments?post=479"}],"version-history":[{"count":106,"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/pages\/479\/revisions"}],"predecessor-version":[{"id":9266,"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/pages\/479\/revisions\/9266"}],"wp:attachment":[{"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/media?parent=479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}