{"id":9287,"date":"2026-08-17T15:54:23","date_gmt":"2026-08-17T15:54:23","guid":{"rendered":"https:\/\/www.saamtowage.com\/guatemala\/blog\/2026\/08\/17\/saam-hunabku-to-be-the-first-tugboat-featuring-imo-tier-iii-technology-in-guatemala\/"},"modified":"2026-08-17T15:58:40","modified_gmt":"2026-08-17T15:58:40","slug":"o-saam-hunabku-sera-o-primeiro-rebocador-da-guatemala-com-tecnologia-imo-tier-iii","status":"publish","type":"post","link":"https:\/\/www.saamtowage.com\/guatemala\/blog\/2026\/08\/17\/o-saam-hunabku-sera-o-primeiro-rebocador-da-guatemala-com-tecnologia-imo-tier-iii\/?lang=pt-br","title":{"rendered":"O SAAM Hunabku ser\u00e1 o primeiro rebocador da Guatemala com tecnologia IMO Tier III"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<!--more--><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<blockquote><p><strong>A nova embarca\u00e7\u00e3o, que operar\u00e1 em Puerto Quetzal, atende aos mais altos padr\u00f5es de controle de emiss\u00f5es de \u00f3xidos de nitrog\u00eanio.<\/strong><\/p><\/blockquote>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Turquia, 30 de julho de 2026<\/strong> | A SAAM Towage incorporar\u00e1 o rebocador SAAM Hunabku \u00e0 sua frota, a 16\u00aa embarca\u00e7\u00e3o entregue pelos estaleiros Sanmar Shipyards \u00e0 companhia. A unidade operar\u00e1 em Puerto Quetzal, Guatemala, como parte do programa de renova\u00e7\u00e3o da frota que a empresa est\u00e1 implementando nas Am\u00e9ricas.<\/p>\n<p>O Diretor de Inova\u00e7\u00e3o e Novas Constru\u00e7\u00f5es da SAAM Towage, Pablo C\u00e1ceres, destacou que \u201co SAAM Hunabku permitir\u00e1 realizar opera\u00e7\u00f5es mais respeitosas com o meio ambiente \u200b\u200bem Puerto Quetzal, por ser o primeiro rebocador IMO Tier III na Guatemala. Este marco reafirma o caminho que definimos para avan\u00e7ar em nossa estrat\u00e9gia de sustentabilidade e reflete o valor da alian\u00e7a que constru\u00edmos com a Sanmar para alcan\u00e7ar nossos objetivos.\u201d<\/p>\n<p>A classifica\u00e7\u00e3o IMO Tier III certifica que os motores atendem aos mais altos padr\u00f5es internacionais de controle de emiss\u00f5es de \u00f3xidos de nitrog\u00eanio (NOx), contribuindo para opera\u00e7\u00f5es mais eficientes e ambientalmente amig\u00e1veis.<\/p>\n<p>Em seguida, o Diretor Comercial dos estaleiros Sanmar Shipyards, R\u00fc\u00e7han \u00c7\u0131vg\u0131n, lembrou que a entrega \u201creflete o compromisso compartilhado de ambas as empresas com a inova\u00e7\u00e3o, a excel\u00eancia operacional e o desenvolvimento de solu\u00e7\u00f5es de reboque sustent\u00e1veis \u200b\u200bpara atender \u00e0s necessidades dos portos modernos\u201d.<\/p>\n<p>Pertencente \u00e0 classe Bo\u011fa\u00e7ay e baseado no projeto RAmparts 2400SX-MKII da Robert Allan, o SAAM Hunabku se destaca por suas dimens\u00f5es compactas \u2014 24,4 metros de comprimento e 12 metros de boca \u2014 combinadas com alta capacidade operacional. A embarca\u00e7\u00e3o pode navegar em velocidades de at\u00e9 12,5 n\u00f3s, est\u00e1 equipada com dois motores CAT 3516E, possui mais de 80 toneladas de for\u00e7a de tra\u00e7\u00e3o est\u00e1tica, sistema de combate a inc\u00eandios FiFi-1, propulsores azimutais duplos (Z-drive) e capacidade para uma tripula\u00e7\u00e3o de at\u00e9 sete pessoas.[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>A nova embarca\u00e7\u00e3o, que operar\u00e1 em Puerto Quetzal, atende aos mais altos padr\u00f5es de controle de emiss\u00f5es de \u00f3xidos de nitrog\u00eanio.<\/p>\n","protected":false},"author":1,"featured_media":9283,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77,54],"tags":[],"class_list":["post-9287","post","type-post","status-publish","format-standard","has-post-thumbnail","category-corporativo-pt-br","category-guatemala-pt-br"],"_links":{"self":[{"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/posts\/9287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/comments?post=9287"}],"version-history":[{"count":2,"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/posts\/9287\/revisions"}],"predecessor-version":[{"id":9293,"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/posts\/9287\/revisions\/9293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/media\/9283"}],"wp:attachment":[{"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/media?parent=9287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/categories?post=9287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.saamtowage.com\/guatemala\/wp-json\/wp\/v2\/tags?post=9287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}